{"id":67855,"date":"2024-07-28T00:01:00","date_gmt":"2024-07-28T04:01:00","guid":{"rendered":"https:\/\/eldiarioantillano.com\/uno\/?p=67855"},"modified":"2024-07-27T20:22:32","modified_gmt":"2024-07-28T00:22:32","slug":"los-discursos-de-echavarria-y-manolo-en-asamblea-1j4","status":"publish","type":"post","link":"https:\/\/eldiarioantillano.com\/uno\/2024\/07\/28\/los-discursos-de-echavarria-y-manolo-en-asamblea-1j4\/","title":{"rendered":"Los discursos de Echavarr\u00eda y Manolo en Asamblea 1J4"},"content":{"rendered":"\n<p>ART\u00cdCULO INVITADO<\/p>\n\n\n\n<p>Por Amaurys P\u00e9rez Vargas<\/p>\n\n\n\n<p>El militante catorcista y periodista&nbsp;<strong>Ra\u00fal P\u00e9rez Pe\u00f1a (Bacho)<\/strong>&nbsp;siempre evoc\u00f3 con orgullo haber cargado sillas durante la realizaci\u00f3n de la Asamblea del Movimiento 14 de Junio del 30 de julio de 1961, la cual se celebr\u00f3 en el segundo piso de la edificaci\u00f3n ubicada en la calle Mercedes # 26 de la Ciudad Colonial. All\u00ed, Dar\u00edo Vinicio Echavarr\u00eda Hern\u00e1ndez pronunci\u00f3 las palabras de apertura, dedicando lo esencial de su intervenci\u00f3n a enumerar los motivos por los que&nbsp;<strong>deb\u00eda luchar el 1J4.<\/strong><\/p>\n\n\n\n<p>Entre esas razones, se\u00f1al\u00f3 que la agrupaci\u00f3n estaba destinada a \u201cluchar por desterrar los males ancestrales del pueblo dominicano, para que nunca jam\u00e1s vuelva a o\u00edrse hablar en Santo Domingo de miedo, de terror, de amenazas, de violaci\u00f3n a los derechos humanos, etc.\u201d.<\/p>\n\n\n\n<p>Tambi\u00e9n alegaba que la naciente organizaci\u00f3n, en su etapa p\u00fablica, deb\u00eda velar por la creaci\u00f3n de \u201clas fuentes de trabajo necesarias para la eliminaci\u00f3n radical del desempleo y sus consecuencias, la miseria, fuentes l\u00f3gicas de indignidades, de servilismo y de humillaciones\u201d.<\/p>\n\n\n\n<p>En ese discurso, marcado por ideas de izquierda, se afirm\u00f3 la necesidad de \u201cla eliminaci\u00f3n de privilegios familiares en raz\u00f3n de apellidos y de posiciones econ\u00f3micas y que solo impere el privilegio de la capacidad y la honestidad\u201d. Abog\u00f3 Echavarr\u00eda en la tribuna por \u201cla erradicaci\u00f3n de la ignorancia y el primitivismo, que impiden al ciudadano el derecho al justo discernimiento, y a la comprensi\u00f3n cabal de qu\u00e9 es lo bueno y qu\u00e9 es lo malo, y de qui\u00e9nes son los malos, y qu\u00e9 le hace ser v\u00edctima de enga\u00f1os y fechor\u00edas mal intencionadas\u201d. De igual forma, reivindic\u00f3 que \u201cla honestidad en la cosa p\u00fablica sea una norma imprescindible para el ejercicio de funciones gubernamentales\u201d.<\/p>\n\n\n\n<p>Se recuerda que los Echavarr\u00eda eran una familia compuesta por cinco hermanos, entre los que estaban Ligia, Mairen\u00ed, Rub\u00e9n, Dinorah y el propio Vinicio, los cuales sufrieron en carne propia el precio de ser antitrujillistas por su militancia en la Juventud Democr\u00e1tica y luego en el Movimiento Clandestino.<\/p>\n\n\n\n<p>Luego de ese discurso, el maestro de ceremonia,&nbsp;<strong>Luis Jos\u00e9 Germ\u00e1n<\/strong>, llam\u00f3 a votaci\u00f3n, cuyos resultados, seg\u00fan nos dice Juan Jos\u00e9 Cruz Segura en su libro Bajo la barbarie, \u201cparieron un Comit\u00e9 Central de 14 miembros, n\u00famero simb\u00f3lico pero par, y, adem\u00e1s de esto, de los miembros elegidos, la mitad respond\u00eda a compromisos ya contra\u00eddos con la UCN: Luis \u00c1lvarez, Miguel Lama, Lic. Rafael Alburquerque, Dra. Asela Morel, Ram\u00f3n Imbert, Arq. Manuel Baquero y Dr. Jos\u00e9 Fern\u00e1ndez Caminero\u201d.<\/p>\n\n\n\n<p>Esta conformaci\u00f3n ayuda a entender un aspecto importante reiterado por Bacho en varios escritos sobre la historia del catorcismo, en los que subrayaba c\u00f3mo en la Asamblea se \u201caprob\u00f3 pasar a la vida p\u00fablica y sustituir el nombre de Movimiento Revolucionario 14 de Junio por el de Agrupaci\u00f3n Pol\u00edtica 14 de Junio\u201d, como una especie de acuerdo o concesi\u00f3n al ala conservadora del movimiento. Desde la perspectiva de Cruz Segura, en esa elecci\u00f3n radic\u00f3 \u201cla dificultad para tomar decisiones definitorias, en particular sobre la l\u00ednea pol\u00edtica de la Agrupaci\u00f3n, su desarrollo y su control\u201d.<\/p>\n\n\n\n<p>Una vez ejercida la votaci\u00f3n,&nbsp;<strong>Manolo Tav\u00e1rez<\/strong>&nbsp;pronunci\u00f3 un discurso en el que traz\u00f3 las pautas pol\u00edticas para la organizaci\u00f3n verde y negra, cuyos ejes centrales fueron, seg\u00fan sus propias palabras:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Asumir \u201ctodas las responsabilidades que conlleva el cumplimiento de sus deberes, al mismo tiempo que declara solemnemente ante ustedes la firme determinaci\u00f3n que los anima a luchar infatigablemente hasta la realizaci\u00f3n de nuestros anhelos, encaminados a satisfacer las leg\u00edtimas aspiraciones de nuestro pueblo\u201d.<\/li>\n\n\n\n<li>Declarar que la ideolog\u00eda del movimiento se inspiraba \u201cen los nobles postulados de la democracia representativa y sus principios se nutren, fundamentalmente, de la Declaraci\u00f3n Universal de los Derechos Humanos\u201d.<\/li>\n\n\n\n<li>Evocar al autor intelectual del Cuartel Moncada para ajustar \u201cnuestras conductas al sublime pensamiento de Jos\u00e9 Mart\u00ed: la patria es ara, no pedestal\u201d.<\/li>\n\n\n\n<li>Invocar al \u201cDios eterno, Padre de las bondades infinitas, implorando sus bendiciones para nuestra agrupaci\u00f3n naciente, para el noble pueblo dominicano\u201d.<\/li>\n<\/ol>\n\n\n\n<p>Esa cita de Mart\u00ed no fue inocente ni tampoco su contenido, teniendo en cuenta el contexto hist\u00f3rico, sobre todo luego de la proclamaci\u00f3n del car\u00e1cter socialista de la Revoluci\u00f3n cubana, de un lado, y, del otro, la influencia que ejerc\u00eda en el seno de la organizaci\u00f3n el sector que se hab\u00eda integrado en la Uni\u00f3n C\u00edvica Nacional, la cual, seg\u00fan Leandro Guzm\u00e1n, se identificaba \u201ccomo un Movimiento basado en los principios de la no-violencia y el anticomunismo, adjetivos capaces de inspirar gran simpat\u00eda a los Estados Unidos\u201d. Ciertamente, las contradicciones con ese grupo todav\u00eda no hab\u00edan aflorado, por lo que toca entender las palabras de Manolo en dos direcciones: primero, en un esfuerzo por marcar distancia; y segundo, por mantener los v\u00ednculos, ya que en esos momentos ambas entidades ten\u00edan objetivos pol\u00edticos comunes concentrados en \u201cla necesidad de luchar contra la presencia del trujillato en aquella nueva etapa\u201d.<\/p>\n\n\n\n<p>Siguiendo a Leandro Guzm\u00e1n, autor del libro De espigas y de fuegos, \u201clas estructuras de poder del tirano estaban principalmente representadas por el entonces presidente Joaqu\u00edn Balaguer, sus generales y colaboradores, apoyados todos por el hijo predilecto del s\u00e1trapa: Ramfis Trujillo\u201d. Nos agrega Guzm\u00e1n que \u201clas primeras acciones, ahora p\u00fablicas y anunciadas, estuvieron dirigidas a organizarnos y contactar a todos los que hab\u00edan militado en la organizaci\u00f3n clandestina\u201d.<\/p>\n\n\n\n<p>En ese orden, Ra\u00fal P\u00e9rez Pe\u00f1a nos indica que \u201cla salida del 14 de Junio a la luz p\u00fablica, lo proyect\u00f3 en t\u00e9rminos masivos en todo el territorio nacional, con comit\u00e9s provinciales y municipales liderados casi siempre por expresos pol\u00edticos, que hab\u00edan luchado en la clandestinidad antitrujillista\u201d.<\/p>\n\n\n\n<p>El desarrollo de esas estructuras partidiarias y de esa vida y militancia pol\u00edtica del 14 de Junio ser\u00e1 el tema de las pr\u00f3ximas entregas de esta serie.<\/p>\n\n\n\n<p>Amaurys P\u00e9rez<br>Soci\u00f3logo e historiador<br>Museo de la Dignidad<\/p>\n\n\n\n<p>Reproducido de Hoy.com.do<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ART\u00cdCULO INVITADO Por Amaurys P\u00e9rez Vargas El militante catorcista y periodista&nbsp;Ra\u00fal P\u00e9rez Pe\u00f1a (Bacho)&nbsp;siempre evoc\u00f3&hellip;<\/p>\n","protected":false},"author":2,"featured_media":67856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-67855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/posts\/67855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/comments?post=67855"}],"version-history":[{"count":1,"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/posts\/67855\/revisions"}],"predecessor-version":[{"id":67857,"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/posts\/67855\/revisions\/67857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/media\/67856"}],"wp:attachment":[{"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/media?parent=67855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/categories?post=67855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiarioantillano.com\/uno\/wp-json\/wp\/v2\/tags?post=67855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}